{"id":5090,"date":"2024-08-08T08:19:56","date_gmt":"2024-08-08T06:19:56","guid":{"rendered":"https:\/\/freunde-fluechtlingssolidaritaet.org\/?p=5090"},"modified":"2024-09-23T12:35:16","modified_gmt":"2024-09-23T10:35:16","slug":"protestkundgebung-am-7-august-auf-dem-kurt-piehl-platz-durchgefuehrt","status":"publish","type":"post","link":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/protestkundgebung-am-7-august-auf-dem-kurt-piehl-platz-durchgefuehrt","title":{"rendered":"Protestkundgebung, am 7. August, auf dem Kurt-Piehl-Platz durchgef\u00fchrt"},"content":{"rendered":"<p>Der Freundeskreis Mouhamed hat mit \u00fcber 25 Leuten eine Protestkundgebung, am 7. August, auf dem Kurt-Piehl-Platz durchgef\u00fchrt. Kulturvoll mit Liedern, Gru\u00dfworten bis aus S\u00fcdafrika und einer Schweigeminute wurde die Veranstaltung begangen. Protestiert wurde gegen den Prozessverlauf und die Forderung der l\u00fcckenlosen Aufkl\u00e4rung und Bestrafung aller Verantwortlichen in Polizei und Politik f\u00fcr den Tod von Mouhamed Lamine Dram\u00e9 stand im Mittelpunkt.&nbsp;<\/p>\n\n\n\n<p>Peter Klusmann, vom Rechtsanwaltsb\u00fcro Meister und Partner geht darauf ein: &#8222;Es ist kaum hinnehmbar, dass belastende Beweisst\u00fccke nicht zugelassen und entsprechende Antr\u00e4ge der Nebenkl\u00e4ger mit Zustimmung des Anklagevertreters der Staatsanwaltschaft abgelehnt wurden.&#8220; Der Verlauf des Prozess ist katastrophal, davon muss die Breite \u00d6ffentlichkeit erfahren und weiterhin der Protest organisiert werden.<\/p>\n\n\n\n<p>Heute am 08.08, Todestag, der Freundeskreis Mohamed einen Kranz niederlegen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-1024x768.jpg\" alt=\"\" class=\"wp-image-5091\" style=\"width:1188px;height:auto\" srcset=\"https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-1024x768.jpg 1024w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-300x225.jpg 300w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-768x576.jpg 768w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-1536x1152.jpg 1536w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-2048x1536.jpg 2048w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/20240807_1809041-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Pressemeldung des \u201eFreundeskreis Mouhamed\u201c im \u201eFreundeskreis Fl\u00fcchtlingssolidarit\u00e4t\u201c<\/strong><\/p>\n\n\n\n<p>\u201eHeute morgen legten Mitglieder des Freundeskreises Mouhamed Lamine Dram\u00e9 an der Gedenktafel am Ort seiner Ermordung einen Kranz nieder. Vor genau zwei Jahren war der 16 J\u00e4hrige Fl\u00fcchtling aus dem Senegal von der Polizei erschossen worden. Statt psychologischer Hilfe f\u00fcr den Selbstmordgef\u00e4hrdeten brachten sie ihm den Tod. Das w\u00fcrdige Gedenken an diesem 2. Jahrestag ist zugleich ein Protest gegen die Prozessf\u00fchrung. Bereits am Vortag fanden Gedenk- und Protestkundgebungen statt, zun\u00e4chst w\u00e4hrend des Prozesses vor dem Landgericht<br>und am fr\u00fchen Abend auf dem Kurt Piehl Platz.<strong> \u201eGerechtigkeit f\u00fcr Mouhamed!\u201c<\/strong> war von Anfang an die Losung des Freundeskreises. Unter dieser Losung hatte sich eine breiteste Solidarit\u00e4t mit Mouhamed entwickelt. Jetzt soll im noch laufenden Prozess die Polizeigewalt als <strong>\u201eNotwehr\u201c <\/strong>gerechtfertigt werden. Die Kranzniederlegung und die Protestkundgebungen machten deutlich: Gedenken hei\u00dft deshalb weiterhin: Solidarit\u00e4t f\u00fcr Mouhamed, gegen Rassismus und wachsende Polizeigewalt, gegen die reaktion\u00e4re Fl\u00fcchtlingspolitik und gegen Faschismus.\u201c<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"761\" src=\"https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-1024x761.jpg\" alt=\"\" class=\"wp-image-5094\" style=\"width:1184px;height:auto\" srcset=\"https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-1024x761.jpg 1024w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-300x223.jpg 300w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-768x571.jpg 768w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-1536x1142.jpg 1536w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-2048x1522.jpg 2048w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-2-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"1024\" src=\"https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-668x1024.jpg\" alt=\"\" class=\"wp-image-5095\" style=\"width:1180px;height:auto\" srcset=\"https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-668x1024.jpg 668w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-196x300.jpg 196w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-768x1177.jpg 768w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-1002x1536.jpg 1002w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-1336x2048.jpg 1336w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-8x12.jpg 8w, https:\/\/freunde-fluechtlingssolidaritaet.org\/wp-content\/uploads\/2024\/08\/2-Todestag-Mouhamed-Bild-3-scaled.jpg 1670w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Der Freundeskreis Mouhamed hat mit \u00fcber 25 Leuten eine Protestkundgebung, am 7. August, auf dem Kurt-Piehl-Platz durchgef\u00fchrt. Kulturvoll mit Liedern, Gru\u00dfworten bis aus S\u00fcdafrika und&hellip;<\/p>","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[55,309],"tags":[314,335,337,339,341,343,345],"class_list":["post-5090","post","type-post","status-publish","format-standard","hentry","category-aktuelles","category-presse-de","tag-aktuelles","tag-justice4mohamed-de","tag-mohamed-de","tag-polizeigewalt-de","tag-presse-de","tag-prozess-de","tag-soli4mohamed-de"],"_links":{"self":[{"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/posts\/5090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/comments?post=5090"}],"version-history":[{"count":2,"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/posts\/5090\/revisions"}],"predecessor-version":[{"id":5096,"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/posts\/5090\/revisions\/5096"}],"wp:attachment":[{"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/media?parent=5090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/categories?post=5090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freunde-fluechtlingssolidaritaet.org\/fa\/wp-json\/wp\/v2\/tags?post=5090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}